{"id":5636,"date":"2024-08-23T11:56:57","date_gmt":"2024-08-23T11:56:57","guid":{"rendered":"https:\/\/ludo-formati.ch\/?p=5636"},"modified":"2024-09-03T17:33:17","modified_gmt":"2024-09-03T17:33:17","slug":"meccaniche-di-gioco","status":"publish","type":"post","link":"https:\/\/ludo-formati.ch\/en\/meccaniche-di-gioco\/","title":{"rendered":"Meccaniche di gioco"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5636\" class=\"elementor elementor-5636\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9a29d2 e-flex e-con-boxed e-con e-parent\" data-id=\"2c9a29d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33e69a58 elementor-widget elementor-widget-image\" data-id=\"33e69a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?fit=1024%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-5655\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?resize=768%2C768&amp;ssl=1 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155e1564 elementor-widget elementor-widget-heading\" data-id=\"155e1564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Meccaniche di gioco<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67bf2688 elementor-widget elementor-widget-heading\" data-id=\"67bf2688\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cosa sono le meccaniche di gioco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f444f8a elementor-widget elementor-widget-text-editor\" data-id=\"3f444f8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le meccaniche di gioco sono il fulcro delle azioni dei giocatori, costituendo un insieme di regole che determinano come le risorse interagiscono tra loro per generare effetti concreti all&#8217;interno del gioco. Questi effetti si manifestano sotto forma di dinamiche ed emozioni, che contribuiscono in modo significativo al coinvolgimento dei partecipanti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16f0e49d elementor-widget elementor-widget-heading\" data-id=\"16f0e49d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le meccaniche nel game design<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec755c7 elementor-widget elementor-widget-text-editor\" data-id=\"1ec755c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le meccaniche di gioco rappresentano uno dei pilastri fondamentali del game design. Secondo il modello MDA (Meccaniche, Dinamiche, Estetica), la progettazione di un&#8217;esperienza di gioco &#8211; sia essa ludica o didattica &#8211; richiede una chiara definizione di queste componenti, insieme alle dinamiche e agli aspetti estetici (o metaforici, nel caso dello storytelling). Tuttavia, in ambito formativo, il modello MDA da solo non \u00e8 sufficiente. \u00c8 essenziale integrare anche gli obiettivi didattici e le emozioni, siano esse positive o negative, che si desidera suscitare attraverso l&#8217;esperienza di gioco. Questo \u00e8 particolarmente importante quando l&#8217;attivit\u00e0 si svolge in asincrono, senza la presenza di un formatore che possa moderare le reazioni dei partecipanti. In tali contesti, il progettista deve prevedere e gestire con attenzione le emozioni che il gioco potr\u00e0 suscitare.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-469e9ade elementor-widget elementor-widget-heading\" data-id=\"469e9ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le meccaniche nella Ludodidattica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79ab6d7f elementor-widget elementor-widget-text-editor\" data-id=\"79ab6d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nella progettazione di attivit\u00e0 didattiche, pu\u00f2 essere estremamente vantaggioso incorporare alcune meccaniche provenienti dal game design, anche senza trasformare l&#8217;intera attivit\u00e0 in un gioco. Questo approccio pu\u00f2 rendere le attivit\u00e0 pi\u00f9 coinvolgenti e motivanti. Ad esempio, invece di proporre un semplice esercizio di calcolo matematico, perch\u00e9 non introdurre due meccaniche di gioco che possano arricchire l&#8217;esperienza e stimolare maggiormente l&#8217;interesse degli studenti?<\/p><p>Si potrebbe progettare un\u2019avventura strutturata a <strong>livelli<\/strong>, in cui i partecipanti interpretano il ruolo di un architetto al servizio del faraone nell\u2019antico Egitto. L\u2019obiettivo finale \u00e8 diventare il Mastro Architetto dell\u2019Impero, ma per raggiungere questo traguardo \u00e8 necessario <strong>collezionare<\/strong> una serie di oggetti speciali. Per ottenerli, gli studenti dovranno affrontare una serie di mini-game tematici incentrati sulla costruzione di piramidi e monumenti. Questi giochi li sfideranno a risolvere problemi matematici legati alla progettazione e costruzione, integrando la teoria con la pratica in modo stimolante e coinvolgente.<\/p><p>Oppure si potrebbe immaginare un\u2019esperienza pensata per imprenditori e imprenditrici. Potrebbe trattarsi di un percorso a <strong>QUEST<\/strong>, dove i partecipanti assumono il ruolo di giovani imprenditori che stanno costruendo il loro impero commerciale. L\u2019obiettivo \u00e8 trasformare la propria startup in un\u2019azienda leader nel settore. Per farlo, devono <strong>COLLEZIONARE<\/strong> risorse chiave, come investimenti, alleanze strategiche e brevetti innovativi. Ogni risorsa viene guadagnata superando una serie di sfide e COMPETERE con la concorrenza o con altri attori nel mercato: negoziazioni con investitori, gestione delle risorse umane, sviluppo del prodotto e strategie di marketing.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79bcdeae elementor-widget elementor-widget-heading\" data-id=\"79bcdeae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Consigli per la progettazione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d04bee3 elementor-widget elementor-widget-text-editor\" data-id=\"d04bee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante la progettazione di un&#8217;attivit\u00e0 didattica, prima di definire l&#8217;attivit\u00e0 stessa e il &#8220;loop&#8221; di azioni che il discente dovr\u00e0 svolgere per acquisire competenze, \u00e8 utile iniziare selezionando alcune meccaniche di gioco da integrare. Questa scelta preliminare consente di strutturare in modo pi\u00f9 efficace le dinamiche, la narrazione e l&#8217;estetica dei materiali didattici, creando un&#8217;esperienza di apprendimento pi\u00f9 coinvolgente e coerente con le meccaniche scelte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11b39c2 elementor-widget elementor-widget-heading\" data-id=\"11b39c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scopri alcune meccaniche di gioco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-706d8aa9 elementor-widget elementor-widget-text-editor\" data-id=\"706d8aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Qui di seguito vi riportiamo alcune meccaniche di gioco che possono venir utilizzate nella progettazione di attivit\u00e0 didattiche. Cliccando sull&#8217;\ud83d\udc41\ufe0f (occhio) potete approfondire la meccanica con una breve spiegazione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b3cdd8 elementor-widget elementor-widget-html\" data-id=\"9b3cdd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"width: 100%;\"><div style=\"position: relative; padding-bottom: 56.25%; padding-top: 0; height: 0;\"><iframe title=\"Meccaniche\" frameborder=\"0\" width=\"1920\" height=\"1080\" style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/view.genially.com\/66d73f05abe8715731e7a9a7\" type=\"text\/html\" allowscriptaccess=\"always\" allowfullscreen=\"true\" scrolling=\"yes\" allownetworking=\"all\"><\/iframe> <\/div> <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Meccaniche di gioco Cosa sono le meccaniche di gioco Le meccaniche di gioco sono il fulcro delle azioni dei giocatori, costituendo un insieme di regole che determinano come le risorse interagiscono tra loro per generare effetti concreti all&#8217;interno del gioco. Questi effetti si manifestano sotto forma di dinamiche ed emozioni, che contribuiscono in modo significativo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ludodidattica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meccaniche di gioco - Ludo-formati.ch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ludo-formati.ch\/en\/meccaniche-di-gioco\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meccaniche di gioco - Ludo-formati.ch\" \/>\n<meta property=\"og:description\" content=\"Meccaniche di gioco Cosa sono le meccaniche di gioco Le meccaniche di gioco sono il fulcro delle azioni dei giocatori, costituendo un insieme di regole che determinano come le risorse interagiscono tra loro per generare effetti concreti all&#8217;interno del gioco. Questi effetti si manifestano sotto forma di dinamiche ed emozioni, che contribuiscono in modo significativo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ludo-formati.ch\/en\/meccaniche-di-gioco\/\" \/>\n<meta property=\"og:site_name\" content=\"Ludo-formati.ch\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-23T11:56:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T17:33:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dario\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/\"},\"author\":{\"name\":\"Dario\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/#\\\/schema\\\/person\\\/13f3f607c178ba3a892ba9c52fd351b0\"},\"headline\":\"Meccaniche di gioco\",\"datePublished\":\"2024-08-23T11:56:57+00:00\",\"dateModified\":\"2024-09-03T17:33:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/\"},\"wordCount\":552,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ludo-formati.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/th-13.jpeg?fit=1024%2C1024&ssl=1\",\"articleSection\":[\"Ludodidattica\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/\",\"url\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/\",\"name\":\"Meccaniche di gioco - Ludo-formati.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ludo-formati.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/th-13.jpeg?fit=1024%2C1024&ssl=1\",\"datePublished\":\"2024-08-23T11:56:57+00:00\",\"dateModified\":\"2024-09-03T17:33:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/#\\\/schema\\\/person\\\/13f3f607c178ba3a892ba9c52fd351b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ludo-formati.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/th-13.jpeg?fit=1024%2C1024&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ludo-formati.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/th-13.jpeg?fit=1024%2C1024&ssl=1\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/meccaniche-di-gioco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ludo-formati.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meccaniche di gioco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/#website\",\"url\":\"https:\\\/\\\/ludo-formati.ch\\\/\",\"name\":\"Ludo-formati.ch\",\"description\":\"Formati, gioca, divertiti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ludo-formati.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ludo-formati.ch\\\/#\\\/schema\\\/person\\\/13f3f607c178ba3a892ba9c52fd351b0\",\"name\":\"Dario\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/584babced9e7ee3133378ae755f48091e9215ae1bc563cc734f7c1342f08f78b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/584babced9e7ee3133378ae755f48091e9215ae1bc563cc734f7c1342f08f78b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/584babced9e7ee3133378ae755f48091e9215ae1bc563cc734f7c1342f08f78b?s=96&d=mm&r=g\",\"caption\":\"Dario\"},\"url\":\"https:\\\/\\\/ludo-formati.ch\\\/en\\\/author\\\/dartog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meccaniche di gioco - Ludo-formati.ch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ludo-formati.ch\/en\/meccaniche-di-gioco\/","og_locale":"en_GB","og_type":"article","og_title":"Meccaniche di gioco - Ludo-formati.ch","og_description":"Meccaniche di gioco Cosa sono le meccaniche di gioco Le meccaniche di gioco sono il fulcro delle azioni dei giocatori, costituendo un insieme di regole che determinano come le risorse interagiscono tra loro per generare effetti concreti all&#8217;interno del gioco. Questi effetti si manifestano sotto forma di dinamiche ed emozioni, che contribuiscono in modo significativo [&hellip;]","og_url":"https:\/\/ludo-formati.ch\/en\/meccaniche-di-gioco\/","og_site_name":"Ludo-formati.ch","article_published_time":"2024-08-23T11:56:57+00:00","article_modified_time":"2024-09-03T17:33:17+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg","type":"image\/jpeg"}],"author":"Dario","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dario","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#article","isPartOf":{"@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/"},"author":{"name":"Dario","@id":"https:\/\/ludo-formati.ch\/#\/schema\/person\/13f3f607c178ba3a892ba9c52fd351b0"},"headline":"Meccaniche di gioco","datePublished":"2024-08-23T11:56:57+00:00","dateModified":"2024-09-03T17:33:17+00:00","mainEntityOfPage":{"@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/"},"wordCount":552,"commentCount":0,"image":{"@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?fit=1024%2C1024&ssl=1","articleSection":["Ludodidattica"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/","url":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/","name":"Meccaniche di gioco - Ludo-formati.ch","isPartOf":{"@id":"https:\/\/ludo-formati.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#primaryimage"},"image":{"@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?fit=1024%2C1024&ssl=1","datePublished":"2024-08-23T11:56:57+00:00","dateModified":"2024-09-03T17:33:17+00:00","author":{"@id":"https:\/\/ludo-formati.ch\/#\/schema\/person\/13f3f607c178ba3a892ba9c52fd351b0"},"breadcrumb":{"@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#primaryimage","url":"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?fit=1024%2C1024&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?fit=1024%2C1024&ssl=1","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/ludo-formati.ch\/meccaniche-di-gioco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ludo-formati.ch\/"},{"@type":"ListItem","position":2,"name":"Meccaniche di gioco"}]},{"@type":"WebSite","@id":"https:\/\/ludo-formati.ch\/#website","url":"https:\/\/ludo-formati.ch\/","name":"Ludo-formati.ch","description":"Formati, gioca, divertiti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ludo-formati.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ludo-formati.ch\/#\/schema\/person\/13f3f607c178ba3a892ba9c52fd351b0","name":"Dario","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/584babced9e7ee3133378ae755f48091e9215ae1bc563cc734f7c1342f08f78b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/584babced9e7ee3133378ae755f48091e9215ae1bc563cc734f7c1342f08f78b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/584babced9e7ee3133378ae755f48091e9215ae1bc563cc734f7c1342f08f78b?s=96&d=mm&r=g","caption":"Dario"},"url":"https:\/\/ludo-formati.ch\/en\/author\/dartog\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ludo-formati.ch\/wp-content\/uploads\/2024\/08\/th-13.jpeg?fit=1024%2C1024&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/posts\/5636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/comments?post=5636"}],"version-history":[{"count":5,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/posts\/5636\/revisions"}],"predecessor-version":[{"id":5661,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/posts\/5636\/revisions\/5661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/media\/5655"}],"wp:attachment":[{"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/media?parent=5636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/categories?post=5636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ludo-formati.ch\/en\/wp-json\/wp\/v2\/tags?post=5636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}